{"id":4143,"date":"2025-06-04T09:21:22","date_gmt":"2025-06-04T07:21:22","guid":{"rendered":"https:\/\/lesterrassesdekersiny.com\/die-maritimen-feste-in-douarnenez\/"},"modified":"2025-07-25T17:21:53","modified_gmt":"2025-07-25T15:21:53","slug":"die-maritimen-feste-in-douarnenez","status":"publish","type":"page","link":"https:\/\/www.lesterrassesdekersiny.com\/de\/die-maritimen-feste-in-douarnenez\/","title":{"rendered":"Die maritimen Feste in Douarnenez"},"content":{"rendered":"<div class=\"experience-header swiper-slide template-block\">\r\n    <div class=\"wrapper PLR-small\">\r\n        <div class=\"left\">\r\n            <div class=\"background absolute\">\r\n                <svg width=\"55\" height=\"51\" viewBox=\"0 0 55 51\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"> <path d=\"M17.3418 43.2504V0.5H20.7026V43.2504H17.3418Z\" fill=\"#697669\" stroke=\"#697669\" \/> <path d=\"M39.7208 12.5727C35.386 12.3391 30.8971 13.2589 26.0854 15.3436C27.7253 9.67971 33.561 5.04966 39.7208 4.71257V12.5727Z\" fill=\"#697669\" stroke=\"#697669\" \/> <path d=\"M38.7577 43.4483C38.7864 42.0464 38.7452 38.8749 37.9939 35.5287L37.7993 34.6623L37.1594 35.278C34.8425 37.507 32.184 40.5091 29.0671 44.3953L29.0663 44.3963C27.486 46.3775 26.036 47.8978 24.4042 48.9269C22.7857 49.9477 20.9641 50.5 18.6145 50.5C18.1194 50.5 17.5659 50.4695 17.0002 50.4152L16.9984 50.4151C13.1156 50.0573 9.16619 47.0292 9.16619 40.9884V25.9116V25.8489L9.15073 25.7882C8.4554 23.0577 6.44061 21.2625 4.51872 20.1297C2.90834 19.1806 1.31844 18.6692 0.5 18.4473V13.4806L8.43053 17.1917L9.14245 17.5249V16.7389V3.00888H12.5349V40.9805C12.5349 43.4707 13.4139 44.9738 14.4949 45.8545C15.5517 46.7156 16.7383 46.9303 17.2949 46.9789C19.2221 47.1613 20.7033 47.0262 22.1291 46.2787C23.5322 45.5432 24.8269 44.2417 26.4511 42.2283L26.4521 42.227C30.3082 37.4147 33.469 33.9028 36.2391 31.4458L36.5312 31.1867L36.3507 30.8405C33.5204 25.4134 27.7378 24.2549 25.7784 24.0128V20.5537C26.7581 20.6486 28.9157 20.9621 31.32 21.9796L31.3219 21.9804C34.0127 23.106 36.9993 25.1016 39.0198 28.6068L39.2804 29.0589L39.7209 28.7792C41.9786 27.346 43.9842 26.7281 45.9506 26.7281C48.2008 26.7281 50.0404 27.7545 51.4097 28.9277C52.4657 29.8326 53.2218 30.8082 53.6447 31.4176L50.6897 33.1342C50.3831 32.7261 49.9049 32.1477 49.2916 31.6129C48.4548 30.8831 47.3081 30.1839 45.9585 30.1839C44.4469 30.1839 42.796 30.8293 40.9347 32.1079L40.6308 32.3167L40.7405 32.6687C42.1856 37.31 42.1677 41.7928 42.1029 43.4483H38.7577Z\" fill=\"#697669\" stroke=\"#697669\" \/>\n<\/svg>            <\/div>\r\n            <div class=\"row-text\">\r\n                <div class=\"surtitle display_medium italic cl-yellow\">Erfahrung 1<\/div>\r\n                <h1 class=\"title headline_large cl-green uppercase\">Die maritimen Feste in Douarnenez<\/h1>\r\n                <div class=\"subtitle headline_xsmall demi futura cl-green uppercase\">Ein unumg\u00e4ngliches Ereignis im Finist\u00e8re<\/div>\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"right\">\r\n            <picture  ><source media=\"(min-width: 1921px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:1333\/h:1500\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_001.jpg\" width=\"1333\" height=\"1500\"><source media=\"(min-width: 1441px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:960\/h:1080\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_001.jpg\" width=\"960\" height=\"1080\"><source media=\"(min-width: 1024px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:720\/h:900\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_001.jpg\" width=\"720\" height=\"900\"><source media=\"(min-width: 769px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:600\/h:656\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_001.jpg\" width=\"600\" height=\"656\"><source media=\"(min-width: 413px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:600\/h:656\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_001.jpg\" width=\"600\" height=\"656\"><source media=\"(min-width: 361px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:376\/h:411\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_001.jpg\" width=\"376\" height=\"411\"><img decoding=\"async\" data-original-width=\"1333\" data-original-height=\"2000\" loading='lazy' class=\"cover unload\" src=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:330\/h:315\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_001.jpg\" alt=\"Les Terrasses de Kersiny - Das maritime Festival von Douarnenez - Altes Segelschiff im Hafen\" width=\"330\" height=\"315\"><\/picture>        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"experience-2-images swiper-slide template-block bg-transparent disposition_1\">\r\n    <div class=\"wrapper\">\r\n        <div class=\"column\">\r\n            <picture  ><source media=\"(min-width: 1441px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:594\/h:320\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_002.jpg\" width=\"594\" height=\"320\"><source media=\"(min-width: 1024px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:427\/h:230\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_002.jpg\" width=\"427\" height=\"230\"><source media=\"(min-width: 769px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:650\/h:498\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_002.jpg\" width=\"650\" height=\"498\"><source media=\"(min-width: 413px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:516\/h:395\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_002.jpg\" width=\"516\" height=\"395\"><source media=\"(min-width: 361px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:328\/h:252\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_002.jpg\" width=\"328\" height=\"252\"><img decoding=\"async\" data-original-width=\"2000\" data-original-height=\"1334\" loading='lazy' class=\"cover unload\" src=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:300\/h:230\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_002.jpg\" alt=\"Les Terrasses de Kersiny - Das maritime Festival von Douarnenez - Hafen von Tr\u00e9boul\" width=\"300\" height=\"230\"><\/picture>\r\n            <div class=\"div-txt\">\r\n                    <div class=\"title headline_large\">7:30<\/div>\r\n    <div class=\"subtitle display_medium italic\">Fr\u00f6hliches Fr\u00fchst\u00fcck vor einem nicht allt\u00e4glichen Tag<\/div>\r\n        <div class=\"paragraph\"><p>Heute Morgen ist die Aufregung gro\u00df: Die F\u00eates Maritimes de Douarnenez finden nur alle zwei Jahre statt, und dieses Jahr sind Sie dabei! Das bedeutet, dass die Aufregung auf dem H\u00f6hepunkt ist. W\u00e4hrend der Kaffee l\u00e4uft und die Kinder ihre Brote schmieren, packen Sie die Taschen: M\u00fctzen, Sonnencreme, Fernglas und Skizzenbuch.  <\/p>\n<p>Fahren Sie zum Hafen von Tr\u00e9boul, eine halbe Stunde vom Campingplatz entfernt.<\/p>\n<\/div>\r\n                <\/div>\r\n        <\/div>\r\n        <div class=\"column\">\r\n            <picture  ><source media=\"(min-width: 1441px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:528\/h:716\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_003.jpg\" width=\"528\" height=\"716\"><source media=\"(min-width: 1024px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:380\/h:515\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_003.jpg\" width=\"380\" height=\"515\"><source media=\"(min-width: 769px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:650\/h:498\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_003.jpg\" width=\"650\" height=\"498\"><source media=\"(min-width: 413px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:516\/h:395\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_003.jpg\" width=\"516\" height=\"395\"><source media=\"(min-width: 361px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:328\/h:252\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_003.jpg\" width=\"328\" height=\"252\"><img decoding=\"async\" data-original-width=\"2000\" data-original-height=\"1000\" loading='lazy' class=\"cover unload\" src=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:300\/h:230\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_003.jpg\" alt=\"Les Terrasses de Kersiny - Das maritime Festival von Douarnenez - Yachthafen\" width=\"300\" height=\"230\"><\/picture>        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"experience-4-images swiper-slide template-block bg-green\">\r\n    <div class=\"wrapper\">\r\n        <div class=\"div-txt\">\r\n                <div class=\"title headline_large\">9:00<\/div>\r\n    <div class=\"subtitle display_medium italic\">Bei der Ankunft in Douarnenez ist die Stimmung bereits auf dem H\u00f6hepunkt.<\/div>\r\n        <div class=\"paragraph\"><p>Sie parken am Stadtrand und nehmen den Shuttlebus, der f\u00fcr diese Gelegenheit eingerichtet wurde. Wenn Sie sich dem Hafen n\u00e4hern, vermischen sich die Kl\u00e4nge: Dudels\u00e4cke, Schiffsglocken, Seemannslieder&#8230; Die Kais sind bereits belebt, bunt und lebendig. Dutzende von traditionellen Segelschiffen liegen vor Anker, einige von ihnen kommen direkt aus Irland, den Niederlanden oder Lateinamerika.  <\/p>\n<p>Die Kinder rennen von einem Mast zum anderen:&nbsp;&#8222;Schaut euch den an, der sieht aus wie ein Piratenschiff!&#8220;.<\/p>\n<\/div>\r\n            <\/div>\r\n                    <div class=\"div-gallery\">\r\n                <div class=\"column\">\r\n                    <picture  ><source media=\"(min-width: 1441px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:594\/h:521\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_004.jpg\" width=\"594\" height=\"521\"><source media=\"(min-width: 1024px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:427\/h:375\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_004.jpg\" width=\"427\" height=\"375\"><source media=\"(min-width: 769px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:500\/h:442\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_004.jpg\" width=\"500\" height=\"442\"><source media=\"(min-width: 413px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:408\/h:361\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_004.jpg\" width=\"408\" height=\"361\"><source media=\"(min-width: 361px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:279\/h:247\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_004.jpg\" width=\"279\" height=\"247\"><img decoding=\"async\" data-original-width=\"2000\" data-original-height=\"1333\" loading='lazy' class=\"cover unload\" src=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:260\/h:230\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_004.jpg\" alt=\"Les Terrasses de Kersiny - Das maritime Festival von Douarnenez - Altes Segelschiff in der Bucht von Douarnenez\" width=\"260\" height=\"230\"><\/picture><picture  ><source media=\"(min-width: 1441px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:594\/h:320\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_006.jpg\" width=\"594\" height=\"320\"><source media=\"(min-width: 1024px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:427\/h:230\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_006.jpg\" width=\"427\" height=\"230\"><source media=\"(min-width: 769px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:500\/h:442\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_006.jpg\" width=\"500\" height=\"442\"><source media=\"(min-width: 413px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:408\/h:361\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_006.jpg\" width=\"408\" height=\"361\"><source media=\"(min-width: 361px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:279\/h:247\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_006.jpg\" width=\"279\" height=\"247\"><img decoding=\"async\" data-original-width=\"2000\" data-original-height=\"1333\" loading='lazy' class=\"cover unload\" src=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:260\/h:230\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_006.jpg\" alt=\"Les Terrasses de Kersiny - Das maritime Festival von Douarnenez - Schiffsglocke\" width=\"260\" height=\"230\"><\/picture>                <\/div>\r\n                <div class=\"column\">\r\n                    <picture  ><source media=\"(min-width: 1441px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:434\/h:420\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_005.jpg\" width=\"434\" height=\"420\"><source media=\"(min-width: 1024px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:312\/h:302\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_005.jpg\" width=\"312\" height=\"302\"><source media=\"(min-width: 769px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:500\/h:442\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_005.jpg\" width=\"500\" height=\"442\"><source media=\"(min-width: 413px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:408\/h:361\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_005.jpg\" width=\"408\" height=\"361\"><source media=\"(min-width: 361px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:279\/h:247\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_005.jpg\" width=\"279\" height=\"247\"><img decoding=\"async\" data-original-width=\"2000\" data-original-height=\"1500\" loading='lazy' class=\"cover unload\" src=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:260\/h:230\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_005.jpg\" alt=\"Les Terrasses de Kersiny - Das maritime Festival von Douarnenez - Seile auf einem Schiff\" width=\"260\" height=\"230\"><\/picture><picture  ><source media=\"(min-width: 1441px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:434\/h:420\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_007.jpg\" width=\"434\" height=\"420\"><source media=\"(min-width: 1024px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:312\/h:302\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_007.jpg\" width=\"312\" height=\"302\"><source media=\"(min-width: 769px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:500\/h:442\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_007.jpg\" width=\"500\" height=\"442\"><source media=\"(min-width: 413px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:408\/h:361\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_007.jpg\" width=\"408\" height=\"361\"><source media=\"(min-width: 361px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:279\/h:247\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_007.jpg\" width=\"279\" height=\"247\"><img decoding=\"async\" data-original-width=\"2000\" data-original-height=\"1333\" loading='lazy' class=\"cover unload\" src=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:260\/h:230\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_007.jpg\" alt=\"\" width=\"260\" height=\"230\"><\/picture>                <\/div>\r\n            <\/div>\r\n            <\/div>\r\n<\/div><div class=\"experience-1-image swiper-slide template-block bg-transparent\">\r\n    <div class=\"wrapper\">\r\n        <div class=\"div-txt\">\r\n                <div class=\"title headline_large\">10:30<\/div>\r\n    <div class=\"subtitle display_medium italic\">Besichtigung der alten Takelagen und erstes Staunen<\/div>\r\n        <div class=\"paragraph\"><p>Sie gehen an Bord einer bretonischen Sloop, dann eines altehrw\u00fcrdigen Dreimasters, wo ein alter Kapit\u00e4n Geschichten \u00fcber die See erz\u00e4hlt, die einen erschauern lassen.<\/p>\n<p>Die Seile, die Segel, die Bl\u00f6cke&#8230; alles ist authentisch. Die Kinder haben gro\u00dfe Augen. Sie atmen diese einzigartige Atmosph\u00e4re zwischen Kulturerbe und Abenteuer ein.  <\/p>\n<\/div>\r\n            <\/div>\r\n                    <picture  ><source media=\"(min-width: 1921px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:1185\/h:1333\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_008.jpg\" width=\"1185\" height=\"1333\"><source media=\"(min-width: 1441px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:960\/h:1080\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_008.jpg\" width=\"960\" height=\"1080\"><source media=\"(min-width: 1024px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:720\/h:900\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_008.jpg\" width=\"720\" height=\"900\"><source media=\"(min-width: 769px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:600\/h:418\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_008.jpg\" width=\"600\" height=\"418\"><source media=\"(min-width: 413px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:497\/h:346\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_008.jpg\" width=\"497\" height=\"346\"><source media=\"(min-width: 361px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:352\/h:245\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_008.jpg\" width=\"352\" height=\"245\"><img decoding=\"async\" data-original-width=\"2000\" data-original-height=\"1333\" loading='lazy' class=\"cover unload\" src=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:330\/h:230\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_008.jpg\" alt=\"Les Terrasses de Kersiny - Das maritime Festival von Douarnenez - Schiff im Yachthafen\" width=\"330\" height=\"230\"><\/picture>            <\/div>\r\n<\/div><div class=\"experience-2-images swiper-slide template-block bg-transparent disposition_2\">\r\n    <div class=\"wrapper\">\r\n        <div class=\"column\">\r\n            <picture  ><source media=\"(min-width: 1441px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:594\/h:320\/q:auto\/rt:fill\/g:we\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_009.jpg\" width=\"594\" height=\"320\"><source media=\"(min-width: 1024px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:427\/h:230\/q:auto\/rt:fill\/g:we\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_009.jpg\" width=\"427\" height=\"230\"><source media=\"(min-width: 769px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:650\/h:498\/q:auto\/rt:fill\/g:we\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_009.jpg\" width=\"650\" height=\"498\"><source media=\"(min-width: 413px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:516\/h:395\/q:auto\/rt:fill\/g:we\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_009.jpg\" width=\"516\" height=\"395\"><source media=\"(min-width: 361px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:328\/h:252\/q:auto\/rt:fill\/g:we\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_009.jpg\" width=\"328\" height=\"252\"><img decoding=\"async\" data-original-width=\"2000\" data-original-height=\"1304\" loading='lazy' class=\"cover unload\" src=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:300\/h:230\/q:auto\/rt:fill\/g:we\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_009.jpg\" alt=\"Les Terrasses de Kersiny - Das maritime Festival von Douarnenez - Traditionelles bretonisches Boot\" width=\"300\" height=\"230\"><\/picture>\r\n            <div class=\"div-txt\">\r\n                    <div class=\"title headline_large\">12:00<\/div>\r\n    <div class=\"subtitle display_medium italic\">Mittagspause in stimmungsvoller Atmosph\u00e4re<\/div>\r\n        <div class=\"paragraph\"><p>Sie finden einen schnellen Tisch mit Blick auf den Hafen. Auf dem Men\u00fc stehen Galettes-saucisses, gegrillte Sardinen und frischer Cidre. Zum Nachtisch gibt es Cr\u00eapes mit Karamell und gesalzener Butter. Ein Bagad spielt eine Fest-Noz Melodie und die Kinder klatschen im Rhythmus.   <\/p>\n<p>Um Sie herum Matrosen in gelben M\u00e4nteln, Musiker aus der ganzen Welt, Kinder, die als Schiffsjungen verkleidet sind&#8230; Sie reisen, ohne die Bretagne zu verlassen.<\/p>\n<\/div>\r\n                <\/div>\r\n        <\/div>\r\n        <div class=\"column\">\r\n            <picture  ><source media=\"(min-width: 1441px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:375\/h:514\/q:auto\/rt:fill\/g:ce\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_010.jpg\" width=\"375\" height=\"514\"><source media=\"(min-width: 1024px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:270\/h:370\/q:auto\/rt:fill\/g:ce\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_010.jpg\" width=\"270\" height=\"370\"><source media=\"(min-width: 769px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:650\/h:498\/q:auto\/rt:fill\/g:ce\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_010.jpg\" width=\"650\" height=\"498\"><source media=\"(min-width: 413px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:516\/h:395\/q:auto\/rt:fill\/g:ce\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_010.jpg\" width=\"516\" height=\"395\"><source media=\"(min-width: 361px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:328\/h:252\/q:auto\/rt:fill\/g:ce\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_010.jpg\" width=\"328\" height=\"252\"><img decoding=\"async\" data-original-width=\"2000\" data-original-height=\"1237\" loading='lazy' class=\"cover unload\" src=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:300\/h:230\/q:auto\/rt:fill\/g:ce\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_010.jpg\" alt=\"Les Terrasses de Kersiny - Das maritime Festival von Douarnenez - Cr\u00eape\" width=\"300\" height=\"230\"><\/picture>        <\/div>\r\n    <\/div>\r\n<\/div><div class=\"experience-4-images swiper-slide template-block bg-transparent\">\r\n    <div class=\"wrapper\">\r\n        <div class=\"div-txt\">\r\n                <div class=\"title headline_large\">14:00<\/div>\r\n    <div class=\"subtitle display_medium italic\">Auff\u00fchrungen, Seemannslieder und Workshops f\u00fcr alle<\/div>\r\n        <div class=\"paragraph\"><p><!-- [if gte mso 9]><xml>\n\n<o:AllowPNG\/>\n\n<\/xml><![endif]--><!-- [if gte mso 9]><xml>\n\nNormal\n0\n<w:TrackMoves\/>\n<w:TrackFormatting\/>\n21\n<w:PunctuationKerning\/>\n<w:ValidateAgainstSchemas\/>\nfalse\nfalse\nfalse\n<w:DoNotPromoteQF\/>\nFR\nX-NONE\nX-NONE\n\n<w:BreakWrappedTables\/>\n<w:SnapToGridInCell\/>\n<w:WrapTextWithPunct\/>\n<w:UseAsianBreakRules\/>\n<w:DontGrowAutofit\/>\n<w:SplitPgBreakAndParaMark\/>\n<w:EnableOpenTypeKerning\/>\n<w:DontFlipMirrorIndents\/>\n<w:OverrideTableStyleHps\/>\n\n\n<m:mathFont m:val=\"Cambria Math\"\/>\n<m:brkBin m:val=\"before\"\/>\n<m:brkBinSub m:val=\"&#45;-\"\/>\n<m:smallFrac m:val=\"off\"\/>\n<m:dispDef\/>\n<m:lMargin m:val=\"0\"\/>\n<m:rMargin m:val=\"0\"\/>\n<m:defJc m:val=\"centerGroup\"\/>\n<m:wrapIndent m:val=\"1440\"\/>\n<m:intLim m:val=\"subSup\"\/>\n<m:naryLim m:val=\"undOvr\"\/>\n\n<\/xml><![endif]--><!-- [if gte mso 9]><xml>\n<w:LatentStyles DefLockedState=\"false\" DefUnhideWhenUsed=\"false\" DefSemiHidden=\"false\" DefQFormat=\"false\" DefPriority=\"99\" LatentStyleCount=\"371\">\n<w:LsdException Locked=\"false\" Priority=\"0\" QFormat=\"true\" Name=\"Normal\"\/>\n<w:LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"9\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"heading 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"9\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"heading 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"9\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"heading 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"9\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"heading 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"9\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"heading 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"9\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"heading 7\"\/>\n<w:LsdException Locked=\"false\" Priority=\"9\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"heading 8\"\/>\n<w:LsdException Locked=\"false\" Priority=\"9\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"heading 9\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index 1\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index 4\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index 5\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index 6\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index 7\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index 8\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index 9\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toc 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toc 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toc 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toc 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toc 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toc 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toc 7\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toc 8\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toc 9\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Normal Indent\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"footnote text\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"annotation text\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"header\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"footer\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index heading\"\/>\n<w:LsdException Locked=\"false\" Priority=\"35\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"caption\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"table of figures\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"envelope address\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"envelope return\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"footnote reference\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"annotation reference\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"line number\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"page number\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"endnote reference\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"endnote text\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"table of authorities\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"macro\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toa heading\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Bullet\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Number\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List 4\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List 5\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Bullet 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Bullet 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Bullet 4\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Bullet 5\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Number 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Number 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Number 4\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Number 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"10\" QFormat=\"true\" Name=\"Title\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Closing\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Signature\"\/>\n<w:LsdException Locked=\"false\" Priority=\"1\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Default Paragraph Font\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Body Text\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Body Text Indent\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Continue\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Continue 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Continue 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Continue 4\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Continue 5\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Message Header\"\/>\n<w:LsdException Locked=\"false\" Priority=\"11\" QFormat=\"true\" Name=\"Subtitle\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Salutation\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Date\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Body Text First Indent\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Body Text First Indent 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Note Heading\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Body Text 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Body Text 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Body Text Indent 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Body Text Indent 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Block Text\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Hyperlink\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"FollowedHyperlink\"\/>\n<w:LsdException Locked=\"false\" Priority=\"22\" QFormat=\"true\" Name=\"Strong\"\/>\n<w:LsdException Locked=\"false\" Priority=\"20\" QFormat=\"true\" Name=\"Emphasis\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Document Map\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Plain Text\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"E-mail Signature\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Top of Form\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Bottom of Form\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Normal (Web)\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Acronym\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Address\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Cite\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Code\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Definition\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Keyboard\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Preformatted\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Sample\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Typewriter\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Variable\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Normal Table\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"annotation subject\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"No List\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Outline List 1\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Outline List 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Outline List 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Simple 1\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Simple 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Simple 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Classic 1\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Classic 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Classic 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Classic 4\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Colorful 1\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Colorful 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Colorful 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Columns 1\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Columns 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Columns 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Columns 4\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Columns 5\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Grid 1\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Grid 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Grid 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Grid 4\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Grid 5\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Grid 6\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Grid 7\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Grid 8\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table List 1\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table List 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table List 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table List 4\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table List 5\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table List 6\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table List 7\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table List 8\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table 3D effects 1\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table 3D effects 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table 3D effects 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Contemporary\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Elegant\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Professional\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Subtle 1\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Subtle 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Web 1\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Web 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Web 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Balloon Text\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" Name=\"Table Grid\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Theme\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" Name=\"Placeholder Text\"\/>\n<w:LsdException Locked=\"false\" Priority=\"1\" QFormat=\"true\" Name=\"No Spacing\"\/>\n<w:LsdException Locked=\"false\" Priority=\"60\" Name=\"Light Shading\"\/>\n<w:LsdException Locked=\"false\" Priority=\"61\" Name=\"Light List\"\/>\n<w:LsdException Locked=\"false\" Priority=\"62\" Name=\"Light Grid\"\/>\n<w:LsdException Locked=\"false\" Priority=\"63\" Name=\"Medium Shading 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"64\" Name=\"Medium Shading 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"65\" Name=\"Medium List 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"66\" Name=\"Medium List 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"67\" Name=\"Medium Grid 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"68\" Name=\"Medium Grid 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"69\" Name=\"Medium Grid 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"70\" Name=\"Dark List\"\/>\n<w:LsdException Locked=\"false\" Priority=\"71\" Name=\"Colorful Shading\"\/>\n<w:LsdException Locked=\"false\" Priority=\"72\" Name=\"Colorful List\"\/>\n<w:LsdException Locked=\"false\" Priority=\"73\" Name=\"Colorful Grid\"\/>\n<w:LsdException Locked=\"false\" Priority=\"60\" Name=\"Light Shading Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"61\" Name=\"Light List Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"62\" Name=\"Light Grid Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"63\" Name=\"Medium Shading 1 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"64\" Name=\"Medium Shading 2 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"65\" Name=\"Medium List 1 Accent 1\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" Name=\"Revision\"\/>\n<w:LsdException Locked=\"false\" Priority=\"34\" QFormat=\"true\" Name=\"List Paragraph\"\/>\n<w:LsdException Locked=\"false\" Priority=\"29\" QFormat=\"true\" Name=\"Quote\"\/>\n<w:LsdException Locked=\"false\" Priority=\"30\" QFormat=\"true\" Name=\"Intense Quote\"\/>\n<w:LsdException Locked=\"false\" Priority=\"66\" Name=\"Medium List 2 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"67\" Name=\"Medium Grid 1 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"68\" Name=\"Medium Grid 2 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"69\" Name=\"Medium Grid 3 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"70\" Name=\"Dark List Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"71\" Name=\"Colorful Shading Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"72\" Name=\"Colorful List Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"73\" Name=\"Colorful Grid Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"60\" Name=\"Light Shading Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"61\" Name=\"Light List Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"62\" Name=\"Light Grid Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"63\" Name=\"Medium Shading 1 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"64\" Name=\"Medium Shading 2 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"65\" Name=\"Medium List 1 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"66\" Name=\"Medium List 2 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"67\" Name=\"Medium Grid 1 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"68\" Name=\"Medium Grid 2 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"69\" Name=\"Medium Grid 3 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"70\" Name=\"Dark List Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"71\" Name=\"Colorful Shading Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"72\" Name=\"Colorful List Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"73\" Name=\"Colorful Grid Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"60\" Name=\"Light Shading Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"61\" Name=\"Light List Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"62\" Name=\"Light Grid Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"63\" Name=\"Medium Shading 1 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"64\" Name=\"Medium Shading 2 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"65\" Name=\"Medium List 1 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"66\" Name=\"Medium List 2 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"67\" Name=\"Medium Grid 1 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"68\" Name=\"Medium Grid 2 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"69\" Name=\"Medium Grid 3 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"70\" Name=\"Dark List Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"71\" Name=\"Colorful Shading Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"72\" Name=\"Colorful List Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"73\" Name=\"Colorful Grid Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"60\" Name=\"Light Shading Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"61\" Name=\"Light List Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"62\" Name=\"Light Grid Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"63\" Name=\"Medium Shading 1 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"64\" Name=\"Medium Shading 2 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"65\" Name=\"Medium List 1 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"66\" Name=\"Medium List 2 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"67\" Name=\"Medium Grid 1 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"68\" Name=\"Medium Grid 2 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"69\" Name=\"Medium Grid 3 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"70\" Name=\"Dark List Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"71\" Name=\"Colorful Shading Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"72\" Name=\"Colorful List Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"73\" Name=\"Colorful Grid Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"60\" Name=\"Light Shading Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"61\" Name=\"Light List Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"62\" Name=\"Light Grid Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"63\" Name=\"Medium Shading 1 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"64\" Name=\"Medium Shading 2 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"65\" Name=\"Medium List 1 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"66\" Name=\"Medium List 2 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"67\" Name=\"Medium Grid 1 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"68\" Name=\"Medium Grid 2 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"69\" Name=\"Medium Grid 3 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"70\" Name=\"Dark List Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"71\" Name=\"Colorful Shading Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"72\" Name=\"Colorful List Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"73\" Name=\"Colorful Grid Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"60\" Name=\"Light Shading Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"61\" Name=\"Light List Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"62\" Name=\"Light Grid Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"63\" Name=\"Medium Shading 1 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"64\" Name=\"Medium Shading 2 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"65\" Name=\"Medium List 1 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"66\" Name=\"Medium List 2 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"67\" Name=\"Medium Grid 1 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"68\" Name=\"Medium Grid 2 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"69\" Name=\"Medium Grid 3 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"70\" Name=\"Dark List Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"71\" Name=\"Colorful Shading Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"72\" Name=\"Colorful List Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"73\" Name=\"Colorful Grid Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"19\" QFormat=\"true\" Name=\"Subtle Emphasis\"\/>\n<w:LsdException Locked=\"false\" Priority=\"21\" QFormat=\"true\" Name=\"Intense Emphasis\"\/>\n<w:LsdException Locked=\"false\" Priority=\"31\" QFormat=\"true\" Name=\"Subtle Reference\"\/>\n<w:LsdException Locked=\"false\" Priority=\"32\" QFormat=\"true\" Name=\"Intense Reference\"\/>\n<w:LsdException Locked=\"false\" Priority=\"33\" QFormat=\"true\" Name=\"Book Title\"\/>\n<w:LsdException Locked=\"false\" Priority=\"37\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Bibliography\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"TOC Heading\"\/>\n<w:LsdException Locked=\"false\" Priority=\"41\" Name=\"Plain Table 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"42\" Name=\"Plain Table 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"43\" Name=\"Plain Table 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"44\" Name=\"Plain Table 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"45\" Name=\"Plain Table 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"40\" Name=\"Grid Table Light\"\/>\n<w:LsdException Locked=\"false\" Priority=\"46\" Name=\"Grid Table 1 Light\"\/>\n<w:LsdException Locked=\"false\" Priority=\"47\" Name=\"Grid Table 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"48\" Name=\"Grid Table 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"49\" Name=\"Grid Table 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"50\" Name=\"Grid Table 5 Dark\"\/>\n<w:LsdException Locked=\"false\" Priority=\"51\" Name=\"Grid Table 6 Colorful\"\/>\n<w:LsdException Locked=\"false\" Priority=\"52\" Name=\"Grid Table 7 Colorful\"\/>\n<w:LsdException Locked=\"false\" Priority=\"46\" Name=\"Grid Table 1 Light Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"47\" Name=\"Grid Table 2 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"48\" Name=\"Grid Table 3 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"49\" Name=\"Grid Table 4 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"50\" Name=\"Grid Table 5 Dark Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"51\" Name=\"Grid Table 6 Colorful Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"52\" Name=\"Grid Table 7 Colorful Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"46\" Name=\"Grid Table 1 Light Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"47\" Name=\"Grid Table 2 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"48\" Name=\"Grid Table 3 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"49\" Name=\"Grid Table 4 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"50\" Name=\"Grid Table 5 Dark Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"51\" Name=\"Grid Table 6 Colorful Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"52\" Name=\"Grid Table 7 Colorful Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"46\" Name=\"Grid Table 1 Light Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"47\" Name=\"Grid Table 2 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"48\" Name=\"Grid Table 3 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"49\" Name=\"Grid Table 4 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"50\" Name=\"Grid Table 5 Dark Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"51\" Name=\"Grid Table 6 Colorful Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"52\" Name=\"Grid Table 7 Colorful Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"46\" Name=\"Grid Table 1 Light Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"47\" Name=\"Grid Table 2 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"48\" Name=\"Grid Table 3 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"49\" Name=\"Grid Table 4 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"50\" Name=\"Grid Table 5 Dark Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"51\" Name=\"Grid Table 6 Colorful Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"52\" Name=\"Grid Table 7 Colorful Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"46\" Name=\"Grid Table 1 Light Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"47\" Name=\"Grid Table 2 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"48\" Name=\"Grid Table 3 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"49\" Name=\"Grid Table 4 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"50\" Name=\"Grid Table 5 Dark Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"51\" Name=\"Grid Table 6 Colorful Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"52\" Name=\"Grid Table 7 Colorful Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"46\" Name=\"Grid Table 1 Light Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"47\" Name=\"Grid Table 2 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"48\" Name=\"Grid Table 3 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"49\" Name=\"Grid Table 4 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"50\" Name=\"Grid Table 5 Dark Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"51\" Name=\"Grid Table 6 Colorful Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"52\" Name=\"Grid Table 7 Colorful Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"46\" Name=\"List Table 1 Light\"\/>\n<w:LsdException Locked=\"false\" Priority=\"47\" Name=\"List Table 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"48\" Name=\"List Table 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"49\" Name=\"List Table 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"50\" Name=\"List Table 5 Dark\"\/>\n<w:LsdException Locked=\"false\" Priority=\"51\" Name=\"List Table 6 Colorful\"\/>\n<w:LsdException Locked=\"false\" Priority=\"52\" Name=\"List Table 7 Colorful\"\/>\n<w:LsdException Locked=\"false\" Priority=\"46\" Name=\"List Table 1 Light Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"47\" Name=\"List Table 2 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"48\" Name=\"List Table 3 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"49\" Name=\"List Table 4 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"50\" Name=\"List Table 5 Dark Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"51\" Name=\"List Table 6 Colorful Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"52\" Name=\"List Table 7 Colorful Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"46\" Name=\"List Table 1 Light Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"47\" Name=\"List Table 2 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"48\" Name=\"List Table 3 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"49\" Name=\"List Table 4 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"50\" Name=\"List Table 5 Dark Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"51\" Name=\"List Table 6 Colorful Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"52\" Name=\"List Table 7 Colorful Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"46\" Name=\"List Table 1 Light Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"47\" Name=\"List Table 2 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"48\" Name=\"List Table 3 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"49\" Name=\"List Table 4 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"50\" Name=\"List Table 5 Dark Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"51\" Name=\"List Table 6 Colorful Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"52\" Name=\"List Table 7 Colorful Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"46\" Name=\"List Table 1 Light Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"47\" Name=\"List Table 2 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"48\" Name=\"List Table 3 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"49\" Name=\"List Table 4 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"50\" Name=\"List Table 5 Dark Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"51\" Name=\"List Table 6 Colorful Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"52\" Name=\"List Table 7 Colorful Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"46\" Name=\"List Table 1 Light Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"47\" Name=\"List Table 2 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"48\" Name=\"List Table 3 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"49\" Name=\"List Table 4 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"50\" Name=\"List Table 5 Dark Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"51\" Name=\"List Table 6 Colorful Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"52\" Name=\"List Table 7 Colorful Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"46\" Name=\"List Table 1 Light Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"47\" Name=\"List Table 2 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"48\" Name=\"List Table 3 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"49\" Name=\"List Table 4 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"50\" Name=\"List Table 5 Dark Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"51\" Name=\"List Table 6 Colorful Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"52\" Name=\"List Table 7 Colorful Accent 6\"\/>\n\n<\/xml><![endif]--><!-- [if gte mso 10]>\n\n\n\n<style>\n \/* Style Definitions *\/<br>\n table.MsoNormalTable<br>\n\t{mso-style-name:\"Tableau Normal\";<br>\n\tmso-tstyle-rowband-size:0;<br>\n\tmso-tstyle-colband-size:0;<br>\n\tmso-style-noshow:yes;<br>\n\tmso-style-priority:99;<br>\n\tmso-style-parent:\"\";<br>\n\tmso-padding-alt:0cm 5.4pt 0cm 5.4pt;<br>\n\tmso-para-margin-top:0cm;<br>\n\tmso-para-margin-right:0cm;<br>\n\tmso-para-margin-bottom:8.0pt;<br>\n\tmso-para-margin-left:0cm;<br>\n\tline-height:107%;<br>\n\tmso-pagination:widow-orphan;<br>\n\tfont-size:11.0pt;<br>\n\tfont-family:\"Calibri\",sans-serif;<br>\n\tmso-ascii-font-family:Calibri;<br>\n\tmso-ascii-theme-font:minor-latin;<br>\n\tmso-hansi-font-family:Calibri;<br>\n\tmso-hansi-theme-font:minor-latin;<br>\n\tmso-bidi-font-family:\"Times New Roman\";<br>\n\tmso-bidi-theme-font:minor-bidi;<br>\n\tmso-fareast-language:EN-US;}<br>\n<\/style>\n\n<![endif]--><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">Sie sehen ein Konzert mit Seemannsliedern auf einer kleinen improvisierten B\u00fchne und dann die spektakul\u00e4ren Man\u00f6ver einer alten Takelage, die unter gro\u00dfem Beifall den Hafen verl\u00e4sst. Am Kai nehmen die Kinder an einem Workshop f\u00fcr Seemannsknoten teil und gehen stolz mit ihrem handgefertigten Armband nach Hause. <\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">Sie k\u00f6nnen auch das maritime Dorf mit seinen Handwerkern und Ausstellungen erkunden: Modelle, Fischernetze, gestreifte Trikots, Holzschuhe aus Douarnenez&#8230; eine Zusammenfassung der bretonischen Kultur unter freiem Himmel.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\r\n            <\/div>\r\n                    <div class=\"div-gallery\">\r\n                <div class=\"column\">\r\n                    <picture  ><source media=\"(min-width: 1441px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:594\/h:521\/q:auto\/rt:fill\/g:ce\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_011.jpg\" width=\"594\" height=\"521\"><source media=\"(min-width: 1024px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:427\/h:375\/q:auto\/rt:fill\/g:ce\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_011.jpg\" width=\"427\" height=\"375\"><source media=\"(min-width: 769px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:500\/h:442\/q:auto\/rt:fill\/g:ce\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_011.jpg\" width=\"500\" height=\"442\"><source media=\"(min-width: 413px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:408\/h:361\/q:auto\/rt:fill\/g:ce\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_011.jpg\" width=\"408\" height=\"361\"><source media=\"(min-width: 361px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:279\/h:247\/q:auto\/rt:fill\/g:ce\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_011.jpg\" width=\"279\" height=\"247\"><img decoding=\"async\" data-original-width=\"2000\" data-original-height=\"1333\" loading='lazy' class=\"cover unload\" src=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:260\/h:230\/q:auto\/rt:fill\/g:ce\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_011.jpg\" alt=\"Les Terrasses de Kersiny - Das maritime Festival von Douarnenez - Miniaturschiff in der Vitrine in einem Gesch\u00e4ft\" width=\"260\" height=\"230\"><\/picture><picture  ><source media=\"(min-width: 1441px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:594\/h:320\/q:auto\/rt:fill\/g:we\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_013.jpg\" width=\"594\" height=\"320\"><source media=\"(min-width: 1024px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:427\/h:230\/q:auto\/rt:fill\/g:we\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_013.jpg\" width=\"427\" height=\"230\"><source media=\"(min-width: 769px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:500\/h:442\/q:auto\/rt:fill\/g:we\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_013.jpg\" width=\"500\" height=\"442\"><source media=\"(min-width: 413px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:408\/h:361\/q:auto\/rt:fill\/g:we\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_013.jpg\" width=\"408\" height=\"361\"><source media=\"(min-width: 361px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:279\/h:247\/q:auto\/rt:fill\/g:we\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_013.jpg\" width=\"279\" height=\"247\"><img decoding=\"async\" data-original-width=\"2000\" data-original-height=\"1333\" loading='lazy' class=\"cover unload\" src=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:260\/h:230\/q:auto\/rt:fill\/g:we\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_013.jpg\" alt=\"Les Terrasses de Kersiny - Das maritime Festival von Douarnenez - Seemannsknoten\" width=\"260\" height=\"230\"><\/picture>                <\/div>\r\n                <div class=\"column\">\r\n                    <picture  ><source media=\"(min-width: 1441px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:434\/h:420\/q:auto\/rt:fill\/g:ce\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_012.jpg\" width=\"434\" height=\"420\"><source media=\"(min-width: 1024px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:312\/h:302\/q:auto\/rt:fill\/g:ce\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_012.jpg\" width=\"312\" height=\"302\"><source media=\"(min-width: 769px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:500\/h:442\/q:auto\/rt:fill\/g:ce\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_012.jpg\" width=\"500\" height=\"442\"><source media=\"(min-width: 413px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:408\/h:361\/q:auto\/rt:fill\/g:ce\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_012.jpg\" width=\"408\" height=\"361\"><source media=\"(min-width: 361px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:279\/h:247\/q:auto\/rt:fill\/g:ce\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_012.jpg\" width=\"279\" height=\"247\"><img decoding=\"async\" data-original-width=\"2000\" data-original-height=\"1333\" loading='lazy' class=\"cover unload\" src=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:260\/h:230\/q:auto\/rt:fill\/g:ce\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_012.jpg\" alt=\"Les Terrasses de Kersiny - Das maritime Festival von Douarnenez - Traditionelle Boote in der Bucht von Douarnenez\" width=\"260\" height=\"230\"><\/picture><picture  ><source media=\"(min-width: 1441px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:434\/h:420\/q:auto\/rt:fill\/g:we\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_014.jpg\" width=\"434\" height=\"420\"><source media=\"(min-width: 1024px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:312\/h:302\/q:auto\/rt:fill\/g:we\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_014.jpg\" width=\"312\" height=\"302\"><source media=\"(min-width: 769px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:500\/h:442\/q:auto\/rt:fill\/g:we\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_014.jpg\" width=\"500\" height=\"442\"><source media=\"(min-width: 413px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:408\/h:361\/q:auto\/rt:fill\/g:we\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_014.jpg\" width=\"408\" height=\"361\"><source media=\"(min-width: 361px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:279\/h:247\/q:auto\/rt:fill\/g:we\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_014.jpg\" width=\"279\" height=\"247\"><img decoding=\"async\" data-original-width=\"2000\" data-original-height=\"1333\" loading='lazy' class=\"cover unload\" src=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:260\/h:230\/q:auto\/rt:fill\/g:we\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_014.jpg\" alt=\"Les Terrasses de Kersiny - Das maritime Festival von Douarnenez - Stapellauf im Hafen von Rosmeur\" width=\"260\" height=\"230\"><\/picture>                <\/div>\r\n            <\/div>\r\n            <\/div>\r\n<\/div><div class=\"experience-1-image swiper-slide template-block bg-green\">\r\n    <div class=\"wrapper\">\r\n        <div class=\"div-txt\">\r\n                <div class=\"title headline_large\">16:00<\/div>\r\n    <div class=\"subtitle display_medium italic\">Express-Baden am Strand von Les Dames<\/div>\r\n        <div class=\"paragraph\"><p>Ein wenig Ruhe, bevor es weitergeht: Sie gehen zu Fu\u00df zum kleinen Strand von Les Dames, wo Sie ein improvisiertes Bad nehmen k\u00f6nnen. Das Wasser ist k\u00fchl, aber erfrischend. Die Kinder planschen lachend, w\u00e4hrend Sie Ihre F\u00fc\u00dfe in den nassen Sand sinken lassen.  <\/p>\n<p>Ein Moment der Stille, weit weg von der Hektik der Kais, aber immer noch vom fernen Klang der maritimen Musik eingelullt.<\/p>\n<\/div>\r\n            <\/div>\r\n                    <picture  ><source media=\"(min-width: 1921px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:1146\/h:1290\/q:auto\/rt:fill\/g:ea\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_015.jpg\" width=\"1146\" height=\"1290\"><source media=\"(min-width: 1441px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:960\/h:1080\/q:auto\/rt:fill\/g:ea\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_015.jpg\" width=\"960\" height=\"1080\"><source media=\"(min-width: 1024px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:720\/h:900\/q:auto\/rt:fill\/g:ea\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_015.jpg\" width=\"720\" height=\"900\"><source media=\"(min-width: 769px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:600\/h:418\/q:auto\/rt:fill\/g:ea\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_015.jpg\" width=\"600\" height=\"418\"><source media=\"(min-width: 413px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:497\/h:346\/q:auto\/rt:fill\/g:ea\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_015.jpg\" width=\"497\" height=\"346\"><source media=\"(min-width: 361px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:352\/h:245\/q:auto\/rt:fill\/g:ea\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_015.jpg\" width=\"352\" height=\"245\"><img decoding=\"async\" data-original-width=\"2000\" data-original-height=\"1290\" loading='lazy' class=\"cover unload\" src=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:330\/h:230\/q:auto\/rt:fill\/g:ea\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_015.jpg\" alt=\"Les Terrasses de Kersiny - Das maritime Festival von Douarnenez - Strand von Les Dames\" width=\"330\" height=\"230\"><\/picture>            <\/div>\r\n<\/div><div class=\"experience-4-images swiper-slide template-block bg-transparent\">\r\n    <div class=\"wrapper\">\r\n        <div class=\"div-txt\">\r\n                <div class=\"title headline_large\">17:30<\/div>\r\n    <div class=\"subtitle display_medium italic\">Parade auf See, der H\u00f6hepunkt des Spektakels<\/div>\r\n        <div class=\"paragraph\"><p>Sie kehren rechtzeitig zur gro\u00dfen Parade an den Kai zur\u00fcck. Alle Segelschiffe laufen in einer majest\u00e4tischen Choreographie aus. Die Segel werden gesetzt, die Wimpel flattern und die Nebelh\u00f6rner ert\u00f6nen. Der Himmel ist blau, das Meer glitzert und Sie alle haben den gleichen Gesichtsausdruck: Staunen.   <\/p>\n<p>Es ist ein magischer, zeitloser Moment. Eine vibrierende Hommage an das Meer und die Menschen, die es erleben. <\/p>\n<\/div>\r\n            <\/div>\r\n                    <div class=\"div-gallery\">\r\n                <div class=\"column\">\r\n                    <picture  ><source media=\"(min-width: 1441px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:594\/h:521\/q:auto\/rt:fill\/g:so\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_019.jpg\" width=\"594\" height=\"521\"><source media=\"(min-width: 1024px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:427\/h:375\/q:auto\/rt:fill\/g:so\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_019.jpg\" width=\"427\" height=\"375\"><source media=\"(min-width: 769px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:500\/h:442\/q:auto\/rt:fill\/g:so\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_019.jpg\" width=\"500\" height=\"442\"><source media=\"(min-width: 413px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:408\/h:361\/q:auto\/rt:fill\/g:so\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_019.jpg\" width=\"408\" height=\"361\"><source media=\"(min-width: 361px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:279\/h:247\/q:auto\/rt:fill\/g:so\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_019.jpg\" width=\"279\" height=\"247\"><img decoding=\"async\" data-original-width=\"2000\" data-original-height=\"1339\" loading='lazy' class=\"cover unload\" src=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:260\/h:230\/q:auto\/rt:fill\/g:so\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_019.jpg\" alt=\"Les Terrasses de Kersiny - Das maritime Festival von Douarnenez - Alte Segelschiffe im Hafen vor Anker\" width=\"260\" height=\"230\"><\/picture><picture  ><source media=\"(min-width: 1441px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:594\/h:320\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_021.jpg\" width=\"594\" height=\"320\"><source media=\"(min-width: 1024px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:427\/h:230\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_021.jpg\" width=\"427\" height=\"230\"><source media=\"(min-width: 769px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:500\/h:442\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_021.jpg\" width=\"500\" height=\"442\"><source media=\"(min-width: 413px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:408\/h:361\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_021.jpg\" width=\"408\" height=\"361\"><source media=\"(min-width: 361px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:279\/h:247\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_021.jpg\" width=\"279\" height=\"247\"><img decoding=\"async\" data-original-width=\"2000\" data-original-height=\"1333\" loading='lazy' class=\"cover unload\" src=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:260\/h:230\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_021.jpg\" alt=\"Les Terrasses de Kersiny - Das maritime Festival von Douarnenez - Maritimes Festival am Ende des Tages\" width=\"260\" height=\"230\"><\/picture>                <\/div>\r\n                <div class=\"column\">\r\n                    <picture  ><source media=\"(min-width: 1441px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:434\/h:420\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_017.jpg\" width=\"434\" height=\"420\"><source media=\"(min-width: 1024px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:312\/h:302\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_017.jpg\" width=\"312\" height=\"302\"><source media=\"(min-width: 769px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:500\/h:442\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_017.jpg\" width=\"500\" height=\"442\"><source media=\"(min-width: 413px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:408\/h:361\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_017.jpg\" width=\"408\" height=\"361\"><source media=\"(min-width: 361px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:279\/h:247\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_017.jpg\" width=\"279\" height=\"247\"><img decoding=\"async\" data-original-width=\"2000\" data-original-height=\"1333\" loading='lazy' class=\"cover unload\" src=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:260\/h:230\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_017.jpg\" alt=\"Les Terrasses de Kersiny - Das maritime Festival von Douarnenez - Inspektion der Segel auf einem Schoner\" width=\"260\" height=\"230\"><\/picture><picture  ><source media=\"(min-width: 1441px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:434\/h:420\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_018.jpg\" width=\"434\" height=\"420\"><source media=\"(min-width: 1024px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:312\/h:302\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_018.jpg\" width=\"312\" height=\"302\"><source media=\"(min-width: 769px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:500\/h:442\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_018.jpg\" width=\"500\" height=\"442\"><source media=\"(min-width: 413px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:408\/h:361\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_018.jpg\" width=\"408\" height=\"361\"><source media=\"(min-width: 361px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:279\/h:247\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_018.jpg\" width=\"279\" height=\"247\"><img decoding=\"async\" data-original-width=\"2000\" data-original-height=\"1333\" loading='lazy' class=\"cover unload\" src=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:260\/h:230\/q:auto\/rt:fill\/g:sm\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_018.jpg\" alt=\"Les Terrasses de Kersiny - Das maritime Festival von Douarnenez - Hafen von Douarnenez\" width=\"260\" height=\"230\"><\/picture>                <\/div>\r\n            <\/div>\r\n            <\/div>\r\n<\/div><div class=\"experience-2-images swiper-slide template-block bg-transparent disposition_1\">\r\n    <div class=\"wrapper\">\r\n        <div class=\"column\">\r\n            <picture  ><source media=\"(min-width: 1441px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:594\/h:320\/q:auto\/rt:fill\/g:ce\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_022.jpg\" width=\"594\" height=\"320\"><source media=\"(min-width: 1024px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:427\/h:230\/q:auto\/rt:fill\/g:ce\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_022.jpg\" width=\"427\" height=\"230\"><source media=\"(min-width: 769px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:650\/h:498\/q:auto\/rt:fill\/g:ce\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_022.jpg\" width=\"650\" height=\"498\"><source media=\"(min-width: 413px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:516\/h:395\/q:auto\/rt:fill\/g:ce\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_022.jpg\" width=\"516\" height=\"395\"><source media=\"(min-width: 361px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:328\/h:252\/q:auto\/rt:fill\/g:ce\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_022.jpg\" width=\"328\" height=\"252\"><img decoding=\"async\" data-original-width=\"1349\" data-original-height=\"2000\" loading='lazy' class=\"cover unload\" src=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:300\/h:230\/q:auto\/rt:fill\/g:ce\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_022.jpg\" alt=\"Les Terrasses de Kersiny - Das maritime Festival von Douarnenez - Boot im Yachthafen w\u00e4hrend des maritimen Festivals\" width=\"300\" height=\"230\"><\/picture>\r\n            <div class=\"div-txt\">\r\n                    <div class=\"title headline_large\">19:00<\/div>\r\n    <div class=\"subtitle display_medium italic\">R\u00fcckkehr zum Campingplatz mit Augen voller Sterne<\/div>\r\n        <div class=\"paragraph\"><p>Die R\u00fcckfahrt ist ruhig und Sie werden von den Erinnerungen an den Tag geschaukelt. Auf dem Campingplatz erwartet Sie ein einfaches Abendessen: Nudelsalat, frisches Brot und Tomme de Brebis. Auf der Terrasse teilen alle ihre Lieblingsmomente des Tages.  <\/p>\n<p>Die Kinder schlafen schnell ein und haben den Kopf voller Boote, bretonischer Musik und salziger Tr\u00e4ume. Sie lassen den Abend ausklingen und beobachten, wie das letzte Licht des Tages \u00fcber die Wellen gleitet&#8230; mit einem einzigen Wunsch: in zwei Jahren wiederzukommen! <\/p>\n<\/div>\r\n                <\/div>\r\n        <\/div>\r\n        <div class=\"column\">\r\n            <picture  ><source media=\"(min-width: 1441px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:528\/h:716\/q:auto\/rt:fill\/g:we\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_020.jpg\" width=\"528\" height=\"716\"><source media=\"(min-width: 1024px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:380\/h:515\/q:auto\/rt:fill\/g:we\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_020.jpg\" width=\"380\" height=\"515\"><source media=\"(min-width: 769px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:650\/h:498\/q:auto\/rt:fill\/g:we\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_020.jpg\" width=\"650\" height=\"498\"><source media=\"(min-width: 413px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:516\/h:395\/q:auto\/rt:fill\/g:we\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_020.jpg\" width=\"516\" height=\"395\"><source media=\"(min-width: 361px)\" srcset=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:328\/h:252\/q:auto\/rt:fill\/g:we\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_020.jpg\" width=\"328\" height=\"252\"><img decoding=\"async\" data-original-width=\"1330\" data-original-height=\"2000\" loading='lazy' class=\"cover unload\" src=\"https:\/\/mldvwi5yf3e6.i.optimole.com\/w:300\/h:230\/q:auto\/rt:fill\/g:we\/https:\/\/www.lesterrassesdekersiny.com\/wp-content\/uploads\/2025\/06\/Les-Terrasses-de-Kersiny_experience_fetes-maritmes-Douarnenez_020.jpg\" alt=\"Les Terrasses de Kersiny - Das maritime Festival von Douarnenez - Boot beim maritimen Festival\" width=\"300\" height=\"230\"><\/picture>        <\/div>\r\n    <\/div>\r\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":2481,"parent":0,"menu_order":36,"comment_status":"closed","ping_status":"closed","template":"templates\/page-experience.php","meta":{"_acf_changed":false,"_seopress_titles_title":"Die F\u00eates Maritimes de Douarnenez | Die Terrassen von Kersiny","_seopress_titles_desc":"Nutzen Sie Ihren Aufenthalt auf dem Campingplatz Les Terrasses de Kersiny, um sich einen unvergesslichen Tag bei den F\u00eates Maritimes de Douarnenez zu g\u00f6nnen!","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"beide","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","footnotes":""},"class_list":["post-4143","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lesterrassesdekersiny.com\/de\/wp-json\/wp\/v2\/pages\/4143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesterrassesdekersiny.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.lesterrassesdekersiny.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesterrassesdekersiny.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesterrassesdekersiny.com\/de\/wp-json\/wp\/v2\/comments?post=4143"}],"version-history":[{"count":2,"href":"https:\/\/www.lesterrassesdekersiny.com\/de\/wp-json\/wp\/v2\/pages\/4143\/revisions"}],"predecessor-version":[{"id":4249,"href":"https:\/\/www.lesterrassesdekersiny.com\/de\/wp-json\/wp\/v2\/pages\/4143\/revisions\/4249"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesterrassesdekersiny.com\/de\/wp-json\/wp\/v2\/media\/2481"}],"wp:attachment":[{"href":"https:\/\/www.lesterrassesdekersiny.com\/de\/wp-json\/wp\/v2\/media?parent=4143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}